{"id":2253,"count":1,"description":"","link":"https:\/\/www.foodconnection.jp\/fc-gourmet\/tag\/%e6%9d%be%e6%b1%9f\/","name":"\u677e\u6c5f","slug":"%e6%9d%be%e6%b1%9f","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.foodconnection.jp\/fc-gourmet\/wp-json\/wp\/v2\/tags\/2253"}],"collection":[{"href":"https:\/\/www.foodconnection.jp\/fc-gourmet\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.foodconnection.jp\/fc-gourmet\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.foodconnection.jp\/fc-gourmet\/wp-json\/wp\/v2\/posts?tags=2253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}